{"id":18311,"date":"2021-11-30T17:00:00","date_gmt":"2021-11-30T15:00:00","guid":{"rendered":"https:\/\/www.libriparlanti.org\/?p=18311"},"modified":"2021-12-04T11:39:41","modified_gmt":"2021-12-04T09:39:41","slug":"30-novembre-ore-17-kids-comics-sulle-tracce-del-dna","status":"publish","type":"post","link":"https:\/\/www.libriparlanti.org\/index.php\/2021\/11\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\/","title":{"rendered":"Marted\u00ec 30 novembre ore 17.00 &#8211; Kids Comics &#8211; Sulle Tracce del DNA"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.libriparlanti.org\/wp-content\/uploads\/2021\/11\/261104142_3891786520924248_7753376998956503211_n.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.libriparlanti.org\/wp-content\/uploads\/2021\/11\/261104142_3891786520924248_7753376998956503211_n-1024x576.jpg\" alt=\"\" class=\"wp-image-18321\" srcset=\"https:\/\/www.libriparlanti.org\/wp-content\/uploads\/2021\/11\/261104142_3891786520924248_7753376998956503211_n-1024x576.jpg 1024w, https:\/\/www.libriparlanti.org\/wp-content\/uploads\/2021\/11\/261104142_3891786520924248_7753376998956503211_n-600x337.jpg 600w, https:\/\/www.libriparlanti.org\/wp-content\/uploads\/2021\/11\/261104142_3891786520924248_7753376998956503211_n-300x169.jpg 300w, https:\/\/www.libriparlanti.org\/wp-content\/uploads\/2021\/11\/261104142_3891786520924248_7753376998956503211_n-768x432.jpg 768w, https:\/\/www.libriparlanti.org\/wp-content\/uploads\/2021\/11\/261104142_3891786520924248_7753376998956503211_n-1536x863.jpg 1536w, https:\/\/www.libriparlanti.org\/wp-content\/uploads\/2021\/11\/261104142_3891786520924248_7753376998956503211_n.jpg 1708w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p>In collaborazione con l&#8217;<a href=\"http:\/\/www.librerieindipendentiragazzi.wordpress.com\/\">Associazione delle Librerie Indipendenti per Ragazzi (ALIR)<\/a> il Kids Comics fa tappa a Castiglione del Lago, si fa per dire, visto che saremo collegati online. Con noi Claudia Flandoli, autrice e illustratrice di<br>SULLE TRACCE DEL DNA, pubblicato da <a href=\"https:\/\/www.editorialescienza.it\/\">Editoriale Scienza<\/a>.<\/p>\n\n\n\n<p>La genetica Raccontata a fumetti<br>Ambra e Blu sono due sorelle gemelle che vogliono sapere perch\u00e9 sono fatte proprio cos\u00ec: perch\u00e9 hanno due occhi e non tre? Perch\u00e9 hanno la pelle chiara e i capelli lisci? E perch\u00e9 si assomigliano come gocce d&#8217;acqua? Diventate microscopiche, esploreranno l&#8217;interno di una cellula del corpo umano accompagnate da Pio, un pulcino saggio che sa rispondere a tutte le loro domande. Durante questo fantastico viaggio alla ricerca del misterioso DNA, attraverseranno le pareti del nucleo e incontreranno un ribosoma alle prime armi, un repressore intrattabile e una piovra gigante che ha un ruolo fondamentale nella divisione della cellula, il centrosoma. Et\u00e0 di lettura: da 11 anni.<\/p>\n\n\n\n<p>Claudia Flandoli &#8211; Torinese di nascita e pisana di adozione, Claudia Flandoli attualmente vive a Cambridge. \u00c8 fumettista e illustratrice scientifica. Ha conseguito la laurea in biologia all\u2019Universit\u00e0 di Pisa e in Progettazione grafica all\u2019Isia di Urbino (Istituto superiore per le industrie artistiche), e si \u00e8 diplomata al master in Illustrazione al MiMaster di Milano.<\/p>\n\n\n\n<p>Collabora come illustratrice con vari ricercatori dell&#8217;Universit\u00e0 di Cambridge, di centri di ricerca legati all&#8217;ateneo (The Gurdon Institute, CIMR &#8211; Cambridge Institute for Medical Research, Lmb &#8211; Laboratory of Molecular Biology) e di altre universit\u00e0 italiane ed europee.<\/p>\n\n\n\n<p>Oltre che con Editoriale Scienza, ha pubblicato fumetti a tema scientifico con Mondadori, Sironi e con il Cnr \u2013 Consiglio nazionale delle ricerche, e ha collaborato con Zanichelli e la Royal Society of Chemistry.<\/p>\n\n\n\n<p>Evento on line in collaborazione con la libreria <a href=\"http:\/\/www.libriparlanti.org\">Libri Parlanti<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=mE1-6Wj3vbk\">https:\/\/www.youtube.com\/watch?v=mE1-6Wj3vbk<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In collaborazione con l&#8217;Associazione delle Librerie Indipendenti per Ragazzi (ALIR) il Kids Comics fa tappa a Castiglione del Lago, si fa per dire, visto che saremo collegati online. Con noi Claudia Flandoli, autrice e illustratrice diSULLE TRACCE DEL DNA, pubblicato da Editoriale Scienza. La genetica Raccontata a fumettiAmbra e Blu sono due sorelle gemelle che [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18312,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"categories":[3],"tags":[],"class_list":["post-18311","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Marted\u00ec 30 novembre ore 17.00 - Kids Comics - Sulle Tracce del DNA - Libreria Libri parlanti<\/title>\n<meta name=\"description\" content=\"marted\u00ec 30 novembre ore 17 in streaming - In collaborazione con l&#039;Associazione delle Librerie Indipendenti per Ragazzi (ALIR) il Kids Comics fa tappa a Castiglione del Lago, si fa per dire, visto che saremo collegati online. Con noi Claudia Flandoli, autrice e illustratrice di SULLE TRACCE DEL DNA, pubblicato da Editoriale Scienza.La genetica Raccontata a fumetti Ambra e Blu sono due sorelle gemelle che vogliono sapere perch\u00e9 sono fatte proprio cos\u00ec: perch\u00e9 hanno due occhi e non tre? Perch\u00e9 hanno la pelle chiara e i capelli lisci? E perch\u00e9 si assomigliano come gocce d&#039;acqua? Diventate microscopiche, esploreranno l&#039;interno di una cellula del corpo umano accompagnate da Pio, un pulcino saggio che sa rispondere a tutte le loro domande. Durante questo fantastico viaggio alla ricerca del misterioso DNA, attraverseranno le pareti del nucleo e incontreranno un ribosoma alle prime armi, un repressore intrattabile e una piovra gigante che ha un ruolo fondamentale nella divisione della cellula, il centrosoma. Et\u00e0 di lettura: da 11 anni.Claudia Flandoli - Torinese di nascita e pisana di adozione, Claudia Flandoli attualmente vive a Cambridge. \u00c8 fumettista e illustratrice scientifica. Ha conseguito la laurea in biologia all\u2019Universit\u00e0 di Pisa e in Progettazione grafica all\u2019Isia di Urbino (Istituto superiore per le industrie artistiche), e si \u00e8 diplomata al master in Illustrazione al MiMaster di Milano. Collabora come illustratrice con vari ricercatori dell&#039;Universit\u00e0 di Cambridge, di centri di ricerca legati all&#039;ateneo (The Gurdon Institute, CIMR - Cambridge Institute for Medical Research, Lmb - Laboratory of Molecular Biology) e di altre universit\u00e0 italiane ed europee.Oltre che con Editoriale Scienza, ha pubblicato fumetti a tema scientifico con Mondadori, Sironi e con il Cnr \u2013 Consiglio nazionale delle ricerche, e ha collaborato con Zanichelli e la Royal Society of Chemistry.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.libriparlanti.org\/index.php\/2021\/11\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marted\u00ec 30 novembre ore 17.00 - Kids Comics - Sulle Tracce del DNA - Libreria Libri parlanti\" \/>\n<meta property=\"og:description\" content=\"marted\u00ec 30 novembre ore 17 in streaming - In collaborazione con l&#039;Associazione delle Librerie Indipendenti per Ragazzi (ALIR) il Kids Comics fa tappa a Castiglione del Lago, si fa per dire, visto che saremo collegati online. Con noi Claudia Flandoli, autrice e illustratrice di SULLE TRACCE DEL DNA, pubblicato da Editoriale Scienza.La genetica Raccontata a fumetti Ambra e Blu sono due sorelle gemelle che vogliono sapere perch\u00e9 sono fatte proprio cos\u00ec: perch\u00e9 hanno due occhi e non tre? Perch\u00e9 hanno la pelle chiara e i capelli lisci? E perch\u00e9 si assomigliano come gocce d&#039;acqua? Diventate microscopiche, esploreranno l&#039;interno di una cellula del corpo umano accompagnate da Pio, un pulcino saggio che sa rispondere a tutte le loro domande. Durante questo fantastico viaggio alla ricerca del misterioso DNA, attraverseranno le pareti del nucleo e incontreranno un ribosoma alle prime armi, un repressore intrattabile e una piovra gigante che ha un ruolo fondamentale nella divisione della cellula, il centrosoma. Et\u00e0 di lettura: da 11 anni.Claudia Flandoli - Torinese di nascita e pisana di adozione, Claudia Flandoli attualmente vive a Cambridge. \u00c8 fumettista e illustratrice scientifica. Ha conseguito la laurea in biologia all\u2019Universit\u00e0 di Pisa e in Progettazione grafica all\u2019Isia di Urbino (Istituto superiore per le industrie artistiche), e si \u00e8 diplomata al master in Illustrazione al MiMaster di Milano. Collabora come illustratrice con vari ricercatori dell&#039;Universit\u00e0 di Cambridge, di centri di ricerca legati all&#039;ateneo (The Gurdon Institute, CIMR - Cambridge Institute for Medical Research, Lmb - Laboratory of Molecular Biology) e di altre universit\u00e0 italiane ed europee.Oltre che con Editoriale Scienza, ha pubblicato fumetti a tema scientifico con Mondadori, Sironi e con il Cnr \u2013 Consiglio nazionale delle ricerche, e ha collaborato con Zanichelli e la Royal Society of Chemistry.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.libriparlanti.org\/index.php\/2021\/11\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\/\" \/>\n<meta property=\"og:site_name\" content=\"Libreria Libri parlanti\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LibriParlanti\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-30T15:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-04T09:39:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.libriparlanti.org\/wp-content\/uploads\/2021\/11\/9788893930055_0_0_0_0-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1336\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.libriparlanti.org\\\/index.php\\\/2021\\\/11\\\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.libriparlanti.org\\\/index.php\\\/2021\\\/11\\\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.libriparlanti.org\\\/#\\\/schema\\\/person\\\/a2101732f0cc0144f0a4d0ecc313655a\"},\"headline\":\"Marted\u00ec 30 novembre ore 17.00 &#8211; Kids Comics &#8211; Sulle Tracce del DNA\",\"datePublished\":\"2021-11-30T15:00:00+00:00\",\"dateModified\":\"2021-12-04T09:39:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.libriparlanti.org\\\/index.php\\\/2021\\\/11\\\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\\\/\"},\"wordCount\":310,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.libriparlanti.org\\\/index.php\\\/2021\\\/11\\\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.libriparlanti.org\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/9788893930055_0_0_0_0.jpeg\",\"articleSection\":[\"eventi\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.libriparlanti.org\\\/index.php\\\/2021\\\/11\\\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.libriparlanti.org\\\/index.php\\\/2021\\\/11\\\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\\\/\",\"url\":\"https:\\\/\\\/www.libriparlanti.org\\\/index.php\\\/2021\\\/11\\\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\\\/\",\"name\":\"Marted\u00ec 30 novembre ore 17.00 - Kids Comics - Sulle Tracce del DNA - Libreria Libri parlanti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.libriparlanti.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.libriparlanti.org\\\/index.php\\\/2021\\\/11\\\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.libriparlanti.org\\\/index.php\\\/2021\\\/11\\\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.libriparlanti.org\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/9788893930055_0_0_0_0.jpeg\",\"datePublished\":\"2021-11-30T15:00:00+00:00\",\"dateModified\":\"2021-12-04T09:39:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.libriparlanti.org\\\/#\\\/schema\\\/person\\\/a2101732f0cc0144f0a4d0ecc313655a\"},\"description\":\"marted\u00ec 30 novembre ore 17 in streaming - In collaborazione con l'Associazione delle Librerie Indipendenti per Ragazzi (ALIR) il Kids Comics fa tappa a Castiglione del Lago, si fa per dire, visto che saremo collegati online. Con noi Claudia Flandoli, autrice e illustratrice di SULLE TRACCE DEL DNA, pubblicato da Editoriale Scienza.La genetica Raccontata a fumetti Ambra e Blu sono due sorelle gemelle che vogliono sapere perch\u00e9 sono fatte proprio cos\u00ec: perch\u00e9 hanno due occhi e non tre? Perch\u00e9 hanno la pelle chiara e i capelli lisci? E perch\u00e9 si assomigliano come gocce d'acqua? Diventate microscopiche, esploreranno l'interno di una cellula del corpo umano accompagnate da Pio, un pulcino saggio che sa rispondere a tutte le loro domande. Durante questo fantastico viaggio alla ricerca del misterioso DNA, attraverseranno le pareti del nucleo e incontreranno un ribosoma alle prime armi, un repressore intrattabile e una piovra gigante che ha un ruolo fondamentale nella divisione della cellula, il centrosoma. Et\u00e0 di lettura: da 11 anni.Claudia Flandoli - Torinese di nascita e pisana di adozione, Claudia Flandoli attualmente vive a Cambridge. \u00c8 fumettista e illustratrice scientifica. Ha conseguito la laurea in biologia all\u2019Universit\u00e0 di Pisa e in Progettazione grafica all\u2019Isia di Urbino (Istituto superiore per le industrie artistiche), e si \u00e8 diplomata al master in Illustrazione al MiMaster di Milano. Collabora come illustratrice con vari ricercatori dell'Universit\u00e0 di Cambridge, di centri di ricerca legati all'ateneo (The Gurdon Institute, CIMR - Cambridge Institute for Medical Research, Lmb - Laboratory of Molecular Biology) e di altre universit\u00e0 italiane ed europee.Oltre che con Editoriale Scienza, ha pubblicato fumetti a tema scientifico con Mondadori, Sironi e con il Cnr \u2013 Consiglio nazionale delle ricerche, e ha collaborato con Zanichelli e la Royal Society of Chemistry.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.libriparlanti.org\\\/index.php\\\/2021\\\/11\\\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.libriparlanti.org\\\/index.php\\\/2021\\\/11\\\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.libriparlanti.org\\\/index.php\\\/2021\\\/11\\\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.libriparlanti.org\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/9788893930055_0_0_0_0.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.libriparlanti.org\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/9788893930055_0_0_0_0.jpeg\",\"width\":1000,\"height\":1336,\"caption\":\"Sulle Tracce del DNA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.libriparlanti.org\\\/index.php\\\/2021\\\/11\\\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.libriparlanti.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marted\u00ec 30 novembre ore 17.00 &#8211; Kids Comics &#8211; Sulle Tracce del DNA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.libriparlanti.org\\\/#website\",\"url\":\"https:\\\/\\\/www.libriparlanti.org\\\/\",\"name\":\"Libreria Libri parlanti\",\"description\":\"Libreria in Castiglione del Lago (Pg)\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.libriparlanti.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.libriparlanti.org\\\/#\\\/schema\\\/person\\\/a2101732f0cc0144f0a4d0ecc313655a\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f06887496a5753f3caca573646570e603d16e07cbd1553492c2c65009e6014ca?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f06887496a5753f3caca573646570e603d16e07cbd1553492c2c65009e6014ca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f06887496a5753f3caca573646570e603d16e07cbd1553492c2c65009e6014ca?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/www.libriparlanti.org\"],\"url\":\"https:\\\/\\\/www.libriparlanti.org\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Marted\u00ec 30 novembre ore 17.00 - Kids Comics - Sulle Tracce del DNA - Libreria Libri parlanti","description":"marted\u00ec 30 novembre ore 17 in streaming - In collaborazione con l'Associazione delle Librerie Indipendenti per Ragazzi (ALIR) il Kids Comics fa tappa a Castiglione del Lago, si fa per dire, visto che saremo collegati online. Con noi Claudia Flandoli, autrice e illustratrice di SULLE TRACCE DEL DNA, pubblicato da Editoriale Scienza.La genetica Raccontata a fumetti Ambra e Blu sono due sorelle gemelle che vogliono sapere perch\u00e9 sono fatte proprio cos\u00ec: perch\u00e9 hanno due occhi e non tre? Perch\u00e9 hanno la pelle chiara e i capelli lisci? E perch\u00e9 si assomigliano come gocce d'acqua? Diventate microscopiche, esploreranno l'interno di una cellula del corpo umano accompagnate da Pio, un pulcino saggio che sa rispondere a tutte le loro domande. Durante questo fantastico viaggio alla ricerca del misterioso DNA, attraverseranno le pareti del nucleo e incontreranno un ribosoma alle prime armi, un repressore intrattabile e una piovra gigante che ha un ruolo fondamentale nella divisione della cellula, il centrosoma. Et\u00e0 di lettura: da 11 anni.Claudia Flandoli - Torinese di nascita e pisana di adozione, Claudia Flandoli attualmente vive a Cambridge. \u00c8 fumettista e illustratrice scientifica. Ha conseguito la laurea in biologia all\u2019Universit\u00e0 di Pisa e in Progettazione grafica all\u2019Isia di Urbino (Istituto superiore per le industrie artistiche), e si \u00e8 diplomata al master in Illustrazione al MiMaster di Milano. Collabora come illustratrice con vari ricercatori dell'Universit\u00e0 di Cambridge, di centri di ricerca legati all'ateneo (The Gurdon Institute, CIMR - Cambridge Institute for Medical Research, Lmb - Laboratory of Molecular Biology) e di altre universit\u00e0 italiane ed europee.Oltre che con Editoriale Scienza, ha pubblicato fumetti a tema scientifico con Mondadori, Sironi e con il Cnr \u2013 Consiglio nazionale delle ricerche, e ha collaborato con Zanichelli e la Royal Society of Chemistry.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.libriparlanti.org\/index.php\/2021\/11\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\/","og_locale":"it_IT","og_type":"article","og_title":"Marted\u00ec 30 novembre ore 17.00 - Kids Comics - Sulle Tracce del DNA - Libreria Libri parlanti","og_description":"marted\u00ec 30 novembre ore 17 in streaming - In collaborazione con l'Associazione delle Librerie Indipendenti per Ragazzi (ALIR) il Kids Comics fa tappa a Castiglione del Lago, si fa per dire, visto che saremo collegati online. Con noi Claudia Flandoli, autrice e illustratrice di SULLE TRACCE DEL DNA, pubblicato da Editoriale Scienza.La genetica Raccontata a fumetti Ambra e Blu sono due sorelle gemelle che vogliono sapere perch\u00e9 sono fatte proprio cos\u00ec: perch\u00e9 hanno due occhi e non tre? Perch\u00e9 hanno la pelle chiara e i capelli lisci? E perch\u00e9 si assomigliano come gocce d'acqua? Diventate microscopiche, esploreranno l'interno di una cellula del corpo umano accompagnate da Pio, un pulcino saggio che sa rispondere a tutte le loro domande. Durante questo fantastico viaggio alla ricerca del misterioso DNA, attraverseranno le pareti del nucleo e incontreranno un ribosoma alle prime armi, un repressore intrattabile e una piovra gigante che ha un ruolo fondamentale nella divisione della cellula, il centrosoma. Et\u00e0 di lettura: da 11 anni.Claudia Flandoli - Torinese di nascita e pisana di adozione, Claudia Flandoli attualmente vive a Cambridge. \u00c8 fumettista e illustratrice scientifica. Ha conseguito la laurea in biologia all\u2019Universit\u00e0 di Pisa e in Progettazione grafica all\u2019Isia di Urbino (Istituto superiore per le industrie artistiche), e si \u00e8 diplomata al master in Illustrazione al MiMaster di Milano. Collabora come illustratrice con vari ricercatori dell'Universit\u00e0 di Cambridge, di centri di ricerca legati all'ateneo (The Gurdon Institute, CIMR - Cambridge Institute for Medical Research, Lmb - Laboratory of Molecular Biology) e di altre universit\u00e0 italiane ed europee.Oltre che con Editoriale Scienza, ha pubblicato fumetti a tema scientifico con Mondadori, Sironi e con il Cnr \u2013 Consiglio nazionale delle ricerche, e ha collaborato con Zanichelli e la Royal Society of Chemistry.","og_url":"https:\/\/www.libriparlanti.org\/index.php\/2021\/11\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\/","og_site_name":"Libreria Libri parlanti","article_publisher":"https:\/\/www.facebook.com\/LibriParlanti","article_published_time":"2021-11-30T15:00:00+00:00","article_modified_time":"2021-12-04T09:39:41+00:00","og_image":[{"width":1000,"height":1336,"url":"https:\/\/www.libriparlanti.org\/wp-content\/uploads\/2021\/11\/9788893930055_0_0_0_0-1.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"admin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.libriparlanti.org\/index.php\/2021\/11\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\/#article","isPartOf":{"@id":"https:\/\/www.libriparlanti.org\/index.php\/2021\/11\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\/"},"author":{"name":"admin","@id":"https:\/\/www.libriparlanti.org\/#\/schema\/person\/a2101732f0cc0144f0a4d0ecc313655a"},"headline":"Marted\u00ec 30 novembre ore 17.00 &#8211; Kids Comics &#8211; Sulle Tracce del DNA","datePublished":"2021-11-30T15:00:00+00:00","dateModified":"2021-12-04T09:39:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.libriparlanti.org\/index.php\/2021\/11\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\/"},"wordCount":310,"commentCount":0,"image":{"@id":"https:\/\/www.libriparlanti.org\/index.php\/2021\/11\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\/#primaryimage"},"thumbnailUrl":"https:\/\/www.libriparlanti.org\/wp-content\/uploads\/2021\/11\/9788893930055_0_0_0_0.jpeg","articleSection":["eventi"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.libriparlanti.org\/index.php\/2021\/11\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.libriparlanti.org\/index.php\/2021\/11\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\/","url":"https:\/\/www.libriparlanti.org\/index.php\/2021\/11\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\/","name":"Marted\u00ec 30 novembre ore 17.00 - Kids Comics - Sulle Tracce del DNA - Libreria Libri parlanti","isPartOf":{"@id":"https:\/\/www.libriparlanti.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.libriparlanti.org\/index.php\/2021\/11\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\/#primaryimage"},"image":{"@id":"https:\/\/www.libriparlanti.org\/index.php\/2021\/11\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\/#primaryimage"},"thumbnailUrl":"https:\/\/www.libriparlanti.org\/wp-content\/uploads\/2021\/11\/9788893930055_0_0_0_0.jpeg","datePublished":"2021-11-30T15:00:00+00:00","dateModified":"2021-12-04T09:39:41+00:00","author":{"@id":"https:\/\/www.libriparlanti.org\/#\/schema\/person\/a2101732f0cc0144f0a4d0ecc313655a"},"description":"marted\u00ec 30 novembre ore 17 in streaming - In collaborazione con l'Associazione delle Librerie Indipendenti per Ragazzi (ALIR) il Kids Comics fa tappa a Castiglione del Lago, si fa per dire, visto che saremo collegati online. Con noi Claudia Flandoli, autrice e illustratrice di SULLE TRACCE DEL DNA, pubblicato da Editoriale Scienza.La genetica Raccontata a fumetti Ambra e Blu sono due sorelle gemelle che vogliono sapere perch\u00e9 sono fatte proprio cos\u00ec: perch\u00e9 hanno due occhi e non tre? Perch\u00e9 hanno la pelle chiara e i capelli lisci? E perch\u00e9 si assomigliano come gocce d'acqua? Diventate microscopiche, esploreranno l'interno di una cellula del corpo umano accompagnate da Pio, un pulcino saggio che sa rispondere a tutte le loro domande. Durante questo fantastico viaggio alla ricerca del misterioso DNA, attraverseranno le pareti del nucleo e incontreranno un ribosoma alle prime armi, un repressore intrattabile e una piovra gigante che ha un ruolo fondamentale nella divisione della cellula, il centrosoma. Et\u00e0 di lettura: da 11 anni.Claudia Flandoli - Torinese di nascita e pisana di adozione, Claudia Flandoli attualmente vive a Cambridge. \u00c8 fumettista e illustratrice scientifica. Ha conseguito la laurea in biologia all\u2019Universit\u00e0 di Pisa e in Progettazione grafica all\u2019Isia di Urbino (Istituto superiore per le industrie artistiche), e si \u00e8 diplomata al master in Illustrazione al MiMaster di Milano. Collabora come illustratrice con vari ricercatori dell'Universit\u00e0 di Cambridge, di centri di ricerca legati all'ateneo (The Gurdon Institute, CIMR - Cambridge Institute for Medical Research, Lmb - Laboratory of Molecular Biology) e di altre universit\u00e0 italiane ed europee.Oltre che con Editoriale Scienza, ha pubblicato fumetti a tema scientifico con Mondadori, Sironi e con il Cnr \u2013 Consiglio nazionale delle ricerche, e ha collaborato con Zanichelli e la Royal Society of Chemistry.","breadcrumb":{"@id":"https:\/\/www.libriparlanti.org\/index.php\/2021\/11\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.libriparlanti.org\/index.php\/2021\/11\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.libriparlanti.org\/index.php\/2021\/11\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\/#primaryimage","url":"https:\/\/www.libriparlanti.org\/wp-content\/uploads\/2021\/11\/9788893930055_0_0_0_0.jpeg","contentUrl":"https:\/\/www.libriparlanti.org\/wp-content\/uploads\/2021\/11\/9788893930055_0_0_0_0.jpeg","width":1000,"height":1336,"caption":"Sulle Tracce del DNA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.libriparlanti.org\/index.php\/2021\/11\/30-novembre-ore-17-kids-comics-sulle-tracce-del-dna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.libriparlanti.org\/"},{"@type":"ListItem","position":2,"name":"Marted\u00ec 30 novembre ore 17.00 &#8211; Kids Comics &#8211; Sulle Tracce del DNA"}]},{"@type":"WebSite","@id":"https:\/\/www.libriparlanti.org\/#website","url":"https:\/\/www.libriparlanti.org\/","name":"Libreria Libri parlanti","description":"Libreria in Castiglione del Lago (Pg)","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.libriparlanti.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.libriparlanti.org\/#\/schema\/person\/a2101732f0cc0144f0a4d0ecc313655a","name":"admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f06887496a5753f3caca573646570e603d16e07cbd1553492c2c65009e6014ca?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f06887496a5753f3caca573646570e603d16e07cbd1553492c2c65009e6014ca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f06887496a5753f3caca573646570e603d16e07cbd1553492c2c65009e6014ca?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/www.libriparlanti.org"],"url":"https:\/\/www.libriparlanti.org\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.libriparlanti.org\/index.php\/wp-json\/wp\/v2\/posts\/18311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.libriparlanti.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.libriparlanti.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.libriparlanti.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.libriparlanti.org\/index.php\/wp-json\/wp\/v2\/comments?post=18311"}],"version-history":[{"count":4,"href":"https:\/\/www.libriparlanti.org\/index.php\/wp-json\/wp\/v2\/posts\/18311\/revisions"}],"predecessor-version":[{"id":18322,"href":"https:\/\/www.libriparlanti.org\/index.php\/wp-json\/wp\/v2\/posts\/18311\/revisions\/18322"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.libriparlanti.org\/index.php\/wp-json\/wp\/v2\/media\/18312"}],"wp:attachment":[{"href":"https:\/\/www.libriparlanti.org\/index.php\/wp-json\/wp\/v2\/media?parent=18311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.libriparlanti.org\/index.php\/wp-json\/wp\/v2\/categories?post=18311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.libriparlanti.org\/index.php\/wp-json\/wp\/v2\/tags?post=18311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}